{"id":493,"date":"2021-06-15T16:49:06","date_gmt":"2021-06-15T16:49:06","guid":{"rendered":"https:\/\/www.nutritive-food.com\/?page_id=493"},"modified":"2021-06-15T17:00:20","modified_gmt":"2021-06-15T17:00:20","slug":"politicas-de-cookies","status":"publish","type":"page","link":"https:\/\/www.nutritive-food.com\/index.php\/politicas-de-cookies\/","title":{"rendered":"Pol\u00edticas de cookies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"493\" class=\"elementor elementor-493\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ea7378 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ea7378\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41ca8290\" data-id=\"41ca8290\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-568580a1 elementor-widget elementor-widget-heading\" data-id=\"568580a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edticas de Cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19285c86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19285c86\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-11f688a4\" data-id=\"11f688a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4f12d9 elementor-widget elementor-widget-text-editor\" data-id=\"a4f12d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario.<\/p><p>El navegador del usuario memoriza cookies en el disco duro solamente durante la sesi\u00f3n actual ocupando un espacio de memoria m\u00ednimo y no perjudicando al ordenador. Las cookies no contienen ninguna clase de informaci\u00f3n personal espec\u00edfica, y la mayor\u00eda de las mismas se borran del disco duro al finalizar la sesi\u00f3n de navegador (las denominadas cookies de sesi\u00f3n).<\/p><p>La mayor\u00eda de los navegadores aceptan como est\u00e1ndar a las cookies y, con independencia de las mismas, permiten o impiden en los ajustes de seguridad las cookies temporales o memorizadas.<\/p><p>Sin su expreso consentimiento \u2013mediante la activaci\u00f3n de las cookies en su navegador\u2013 nutritive-food.com no enlazar\u00e1 en las cookies los datos memorizados con sus datos personales proporcionados en el momento del registro o el ingreso de comentarios en los destinos.<\/p><p><strong>\u00bfQu\u00e9 tipos de cookies utiliza esta p\u00e1gina web?<\/strong><\/p><ul><li><strong>Cookies t\u00e9cnicas<\/strong>: Son aqu\u00e9llas que permiten al usuario la navegaci\u00f3n a trav\u00e9s de una p\u00e1gina web, plataforma o aplicaci\u00f3n y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan como, por ejemplo, controlar el tr\u00e1fico y la comunicaci\u00f3n de datos, identificar la sesi\u00f3n, acceder a partes de acceso restringido, recordar los elementos que integran un pedido, realizar el proceso de compra de un pedido, realizar la solicitud de inscripci\u00f3n o participaci\u00f3n en un evento, utilizar elementos de seguridad durante la navegaci\u00f3n, almacenar contenidos para la difusi\u00f3n de videos o sonido o compartir contenidos a trav\u00e9s de redes sociales.<\/li><li><strong>Cookies de personalizaci\u00f3n<\/strong>: Son aqu\u00e9llas que permiten al usuario acceder al servicio con algunas caracter\u00edsticas de car\u00e1cter general predefinidas en funci\u00f3n de una serie de criterios en el terminal del usuario como por ejemplo serian el idioma, el tipo de navegador a trav\u00e9s del cual accede al servicio, la configuraci\u00f3n regional desde donde accede al servicio, etc.<\/li><li><strong>Cookies de an\u00e1lisis<\/strong>: Son aqu\u00e9llas que bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ello se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos.<\/li><li><strong>Cookies publicitarias<\/strong>: Son aqu\u00e9llas que, bien tratadas por nosotros o por terceros, nos permiten gestionar de la forma m\u00e1s eficaz posible la oferta de los espacios publicitarios que hay en la p\u00e1gina web, adecuando el contenido del anuncio al contenido del servicio solicitado o al uso que realice de nuestra p\u00e1gina web. Para ello podemos analizar sus h\u00e1bitos de navegaci\u00f3n en Internet y podemos mostrarle publicidad relacionada con su perfil de navegaci\u00f3n.<\/li><li><strong>Cookies de publicidad comportamental<\/strong>: Son aqu\u00e9llas que permiten la gesti\u00f3n, de la forma m\u00e1s eficaz posible, de los espacios publicitarios que, en su caso, el editor haya incluido en una p\u00e1gina web, aplicaci\u00f3n o plataforma desde la que presta el servicio solicitado. Estas cookies almacenan informaci\u00f3n del comportamiento de los usuarios obtenida a trav\u00e9s de la observaci\u00f3n continuada de sus h\u00e1bitos de navegaci\u00f3n, lo que permite desarrollar un perfil espec\u00edfico para mostrar publicidad en funci\u00f3n del mismo.<\/li><li><strong>Cookies de terceros<\/strong>: La Web de ecuadoralmundo.com puede utilizar servicios de terceros que, por cuenta de Google, recopilaran informaci\u00f3n con fines estad\u00edsticos, de uso del Site por parte del usuario y para la prestacion de otros servicios relacionados con la actividad del Website y otros servicios de Internet.<\/li><\/ul><p>En particular, este sitio Web utiliza Google Analytics, un servicio anal\u00edtico de web prestado por Google, Inc. con domicilio en los Estados Unidos con sede central en 1600 Amphitheatre Parkway, Mountain View, California 94043. \u00a0Para la prestaci\u00f3n de estos servicios, estos utilizan cookies que recopilan la informaci\u00f3n, incluida la direcci\u00f3n IP del usuario, que ser\u00e1 transmitida, tratada y almacenada por Google en los t\u00e9rminos fijados en la Web Google.com. Incluyendo la posible transmisi\u00f3n de dicha informaci\u00f3n a terceros por razones de exigencia legal o cuando dichos terceros procesen la informaci\u00f3n por cuenta de Google.<\/p><p>El Usuario acepta expresamente, por la utilizaci\u00f3n de este Site, el tratamiento de la informaci\u00f3n recabada en la forma y con los fines anteriormente mencionados. Y asimismo reconoce conocer la posibilidad de rechazar el tratamiento de tales datos o informaci\u00f3n rechazando el uso de Cookies mediante la selecci\u00f3n de la configuraci\u00f3n apropiada a tal fin en su navegador. Si bien esta opci\u00f3n de bloqueo de Cookies en su navegador puede no permitirle el uso pleno de todas las funcionalidades del Website.<\/p><p>Puede usted permitir, bloquear o eliminar las cookies instaladas en su equipo mediante la configuraci\u00f3n de las opciones del navegador instalado en su ordenador:<\/p><p><a href=\"https:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647\">Chrome<\/a><\/p><p><a href=\"http:\/\/windows.microsoft.com\/es-es\/windows7\/how-to-manage-cookies-in-internet-explorer-9\">Explorer<\/a><\/p><p><a href=\"https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\">Firefox<\/a><\/p><p><a href=\"https:\/\/support.apple.com\/kb\/ph21411?locale=es_ES\">Safari<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edticas de Cookies Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"class_list":["post-493","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/pages\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/comments?post=493"}],"version-history":[{"count":7,"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/pages\/493\/revisions"}],"predecessor-version":[{"id":503,"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/pages\/493\/revisions\/503"}],"wp:attachment":[{"href":"https:\/\/www.nutritive-food.com\/index.php\/wp-json\/wp\/v2\/media?parent=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}